{"id":9747,"date":"2026-01-28T12:24:17","date_gmt":"2026-01-28T11:24:17","guid":{"rendered":"https:\/\/schron.szczecin.pl\/super-atrakcja-zwiedzanie\/"},"modified":"2026-05-06T15:54:42","modified_gmt":"2026-05-06T13:54:42","slug":"super-atrakcja-zwiedzanie","status":"publish","type":"page","link":"https:\/\/schron.szczecin.pl\/de\/","title":{"rendered":"Super Atrakcja Zwiedzanie"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9747\" class=\"elementor elementor-9747 elementor-9740\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-710dd72a e-con-full e-flex e-con e-parent\" data-id=\"710dd72a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:1308,&quot;url&quot;:&quot;https:\\\/\\\/schron.szczecin.pl\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/dworzec-lokalizacja-informacja-zwiedzanie-scaled-e1677081183797.jpg&quot;},{&quot;id&quot;:1310,&quot;url&quot;:&quot;https:\\\/\\\/schron.szczecin.pl\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/klatka-schodowa-schron_edited-scaled-e1677081210445.jpg&quot;},{&quot;id&quot;:1312,&quot;url&quot;:&quot;https:\\\/\\\/schron.szczecin.pl\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/mural-podziemny-swiatla-uv-samolot-turystka-zwiedza-scaled-e1677081233949.jpg&quot;},{&quot;id&quot;:1314,&quot;url&quot;:&quot;https:\\\/\\\/schron.szczecin.pl\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/tunele-podziemne-trasy-zwiedzajacy_edited-scaled-e1677081254581.jpg&quot;},{&quot;id&quot;:1316,&quot;url&quot;:&quot;https:\\\/\\\/schron.szczecin.pl\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/tunele-poziomy-schronu-wystawy-podziemne-trasy-scaled-e1677081273239.jpg&quot;},{&quot;id&quot;:1318,&quot;url&quot;:&quot;https:\\\/\\\/schron.szczecin.pl\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/tunel-wystawa-exponaty-wojenne-manekiny-fiat126p-scaled-e1677085520110.jpg&quot;}],&quot;background_slideshow_lazyload&quot;:&quot;yes&quot;,&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-404e015 e-con-full e-flex e-con e-child\" data-id=\"404e015\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1f7bbaac e-con-full e-flex e-con e-child\" data-id=\"1f7bbaac\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-56647968 e-con-full e-flex e-con e-child\" data-id=\"56647968\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a1b8245 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3a1b8245\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Unterirdische Besichtigungsrouten in Stettin<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65350a7 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"65350a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Thematische Ausstellungsgalerie \n<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44bff467 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"44bff467\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Beschreibend auf Deutsch mehr als 60 Ausstellungen f\u00fcr Erwachsene und Kinder. Eine Eintrittskarte erm\u00f6glicht die individuelle Besichtigung von drei verschiedenen Routen, mit Licht, Ton, Filmen und einzigartigen Exponaten. Eingang am Bahnsteig 1.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-47d309ea e-flex e-con-boxed e-con e-parent\" data-id=\"47d309ea\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-70a72214 e-con-full e-flex e-con e-child\" data-id=\"70a72214\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-212f00cf elementor-widget elementor-widget-spacer\" data-id=\"212f00cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1da4803e elementor-invisible elementor-widget elementor-widget-image\" data-id=\"1da4803e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2025\/02\/trasy-piktogram-ludziki.png\" title=\"trasy-piktogram-ludziki\" alt=\"logo podziemne trasy szczecina trzy ludziki czerwony niebieski i z\u00f3\u0142ty trzy trasy zwiedzania\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5910ba50 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"5910ba50\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;bounceInUp&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-2fb1ab03 animated-fast e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"2fb1ab03\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:800}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-798862ea elementor-view-stacked elementor-shape-square elementor-widget__width-initial animated-fast elementor-position-block-start elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"798862ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-grow\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-calendar1\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAktuelle \u00d6ffnungszeiten Einzelbesucher\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<b>Besichtigung<\/b> ohne F\u00fchrer und Reservierung \nDo-Mo  <b>12:00-16:00<\/b><br><br><b>Letzte EIntritt 15:00<\/b><br><br>Laenger im Sommer. <br>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-79609106 animated-fast e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"79609106\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:800}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ea7d834 elementor-view-stacked elementor-shape-square animated-fast elementor-widget__width-initial elementor-position-block-start elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"3ea7d834\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:48605433433\" class=\"elementor-icon elementor-animation-grow\" tabindex=\"-1\" aria-label=\"Gruppen Besichtigung 7 Tagen\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-megaphone1\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"tel:48605433433\" >\n\t\t\t\t\t\t\tGruppen Besichtigung 7 Tagen\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<b>Fuer 25 Personen<\/b> <br>und mehr wir bieten gefuerten Touren an, jeden Tag, jede Stinde, nach Bedarf. <br><b>Angebot fuer die Gruppen <\/b>finden Sie in Menu Seite: klicken Sie GRUPPEN. <br><b>Diese Option<\/b> ist nur nach vorigen Buchung moeglich., am besten per E-mail auf Deutsch auch.Bitte beobachten Sie das Menue in der oberen Leiste. <br>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2568ad00 animated-fast e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"2568ad00\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:600}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55196a81 elementor-view-stacked elementor-shape-square animated-fast elementor-widget__width-initial elementor-position-block-start elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"55196a81\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.google.com\/maps\/place\/Krzysztofa+Kolumba+2,+70-213+Szczecin\/data=!4m2!3m1!1s0x47aa091b5abf99e7:0x24f0d0352f094442?sa=X&#038;ved=2ahUKEwj89o-N3-_8AhXSrIsKHfopAFgQ8gF6BAgdEAI\" class=\"elementor-icon elementor-animation-grow\" tabindex=\"-1\" aria-label=\"Ticketpries, Besichtigung auf eigene Faust, ohne Buchung:\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-coins\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/maps\/place\/Krzysztofa+Kolumba+2,+70-213+Szczecin\/data=!4m2!3m1!1s0x47aa091b5abf99e7:0x24f0d0352f094442?sa=X&#038;ved=2ahUKEwj89o-N3-_8AhXSrIsKHfopAFgQ8gF6BAgdEAI\" >\n\t\t\t\t\t\t\tTicketpries, Besichtigung auf eigene Faust, ohne Buchung:\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<u>50 PLN \/Person <\/u><br>normal\n<u>40  PLN \/<\/u> Erm\u00e4\u00dfigt f\u00fcr Kinder ab 6 Jahre alt\nund Jugendliche bis 18 Jahre, <br>Stettiner Touristenkarte<br>40 PLN<br><u>45 PLN<\/u> \/ Studenten  \n(bis 26 Jahre) Rentner, Behinderten und Senioren <br>ab 65 J.a. , <br>Dis iest ein Angebot fuer individualbesucher. Innertemperatur 14 Grad.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e48ce44 animated-fast e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"6e48ce44\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:600}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4deba178 elementor-view-stacked elementor-shape-square animated-fast elementor-widget__width-initial elementor-position-block-start elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"4deba178\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"mailto:info@schron.szczecin.pl\" class=\"elementor-icon elementor-animation-grow\" tabindex=\"-1\" aria-label=\"1 Ticket 3 Routen:\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-direction\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"mailto:info@schron.szczecin.pl\" >\n\t\t\t\t\t\t\t1 Ticket 3 Routen:\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<b>\"II Welt Krieg\" <br>\n+ \"Kalter Krieg\" <br>\n+ \"Kommunistische Zeiten in Polen\" <br><\/b>\n(Selfie mit Geschichte) <br>\nFotografieren f\u00fcr den pers\u00f6nlichen <br>\nGebrauch ist erlaubt, <br>\nFilmaufnahmen sind nicht gestattet.<br>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-44743178 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"44743178\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:400}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f60f51 elementor-view-stacked elementor-shape-square elementor-widget__width-initial animated-fast elementor-position-block-start elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"9f60f51\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.google.com\/maps\/place\/Krzysztofa+Kolumba+2,+70-213+Szczecin\/data=!4m2!3m1!1s0x47aa091b5abf99e7:0x24f0d0352f094442?sa=X&#038;ved=2ahUKEwj89o-N3-_8AhXSrIsKHfopAFgQ8gF6BAgdEAI\" class=\"elementor-icon elementor-animation-grow\" tabindex=\"-1\" aria-label=\"Adresse\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-map-marker1\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/maps\/place\/Krzysztofa+Kolumba+2,+70-213+Szczecin\/data=!4m2!3m1!1s0x47aa091b5abf99e7:0x24f0d0352f094442?sa=X&#038;ved=2ahUKEwj89o-N3-_8AhXSrIsKHfopAFgQ8gF6BAgdEAI\" >\n\t\t\t\t\t\t\tAdresse\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tKolumba 2, Szczecin <br>\n70-035 Polen \nHauptbahnhof <br>Szczecin G\u0142\u00f3wny <br>\nStation, Gleis 1; <b>Eingang <\/b>durch einen Glashaus mit Treppe runter. <br>Geldautomaten und Toiletten in der Bahnhofshalle. \nWir empfehlen, Bargeld vorzubereiten, vorzugsweise in Euro, da es m\u00f6glicherweise Probleme mit der Verbindung zu Kartenterminals gibt.<br><br>Buchung per email: <b>Info@schron.szczecin.pl<\/b><br>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1057409d e-flex e-con-boxed e-con e-parent\" data-id=\"1057409d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1454ed3f e-con-full e-flex e-con e-child\" data-id=\"1454ed3f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e1b8d79 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-video\" data-id=\"1e1b8d79\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/tAKwn6J4l2o?si=KEK1-zZhfIQyRLpP&quot;,&quot;_animation&quot;:&quot;zoomIn&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5461b72 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5461b72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07bd81d elementor-widget elementor-widget-image\" data-id=\"07bd81d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"150\" src=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2026\/02\/certyfikat-jakosci-DE-300x150.jpg\" class=\"attachment-medium size-medium wp-image-10034\" alt=\"\" srcset=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2026\/02\/certyfikat-jakosci-DE-300x150.jpg 300w, https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2026\/02\/certyfikat-jakosci-DE-1024x512.jpg 1024w, https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2026\/02\/certyfikat-jakosci-DE-768x384.jpg 768w, https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2026\/02\/certyfikat-jakosci-DE.jpg 1170w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54a657f7 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"54a657f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"color: #ffd200; margin-top: 10px;\">Bitte beachten Sie: Schulen, Touristen- und Gesch\u00e4ftsgruppen sind 7 Tage in der Woche willkommen<\/p><p>nach vorheriger Reservierung per E-Mail info@schron.szczecin.pl<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cbfbb5e elementor-widget elementor-widget-spacer\" data-id=\"6cbfbb5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2b6b1f77 e-flex e-con-boxed e-con e-parent\" data-id=\"2b6b1f77\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-18072873 e-con-full e-flex e-con e-child\" data-id=\"18072873\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b5ab6ff elementor-widget elementor-widget-heading\" data-id=\"2b5ab6ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Eintrittspreis<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b1a69ef elementor-widget elementor-widget-text-editor\" data-id=\"4b1a69ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Eintrittspreis f\u00fcr Personen, die nicht in einer Gruppe organisiert sind (d. h. weniger als 15 Personen):<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-660965a6 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"660965a6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t<div class=\"elementor-element elementor-element-3fc434b1 e-con-full e-flex e-con e-child\" data-id=\"3fc434b1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13c0952d elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"13c0952d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-grow\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-user\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tF\u00dcR UNORGANISIERTE PERSONEN BIS ZU 15 PERSONEN:\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<u>45 PLN \/Person<\/u> normal<br>\n\n<u>35 PLN \/<\/u> Erm\u00e4\u00dfigt f\u00fcr Kinder ab 6 Jahre alt und Jugendliche bis 18 Jahre,  Stettiner Touristenkarte<br><u>40 PLN \/<\/u> Studenten (bis 26 Jahre), Rentner, Behinderte\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b9569e e-con-full e-flex e-con e-child\" data-id=\"b9569e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c1680c3 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"4c1680c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-grow\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-price-menu\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRabatte\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<span style=\"font-size: 16px;text-align: start\">Wir bieten Gruppenrabatte ab 15 Personen.\nIm Preis eines Tickets ist die M\u00f6glichkeit enthalten, alle drei Strecken zu sehen<\/span>\n \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-629a438d e-con-full e-flex e-con e-child\" data-id=\"629a438d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf4df0f elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"cf4df0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-grow\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"lnr lnr-users\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGr\u00f6\u00dfere Gruppen\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tGruppen von mehr als 2<u>5 Personen<\/u> werden gebeten, sich vor\nihrer Ankunft mit uns in Verbindung zu setzen. Besichtigungen sind jederzeit\nm\u00f6glich. Angebot f\u00fcr Gruppen auf der Unterseite \u201eGruppen\u201d\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b0624f elementor-widget elementor-widget-spacer\" data-id=\"6b0624f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30ebce37 e-flex e-con-boxed e-con e-parent\" data-id=\"30ebce37\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6057886a e-con-full e-flex e-con e-child\" data-id=\"6057886a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b6f757c elementor-widget elementor-widget-heading\" data-id=\"1b6f757c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Was zu sehen und zu erleben?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4db21dff e-con-full e-flex e-con e-child\" data-id=\"4db21dff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7dce384 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"7dce384\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44124783 elementor-widget elementor-widget-image\" data-id=\"44124783\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2023\/01\/1-tunel-wystawa-exponaty-wojenne-manekiny-fiat126p-turysci-768x512.jpg\" class=\"elementor-animation-grow attachment-medium_large size-medium_large wp-image-1416\" alt=\"Podziemne Trasy Szczecina\" srcset=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2023\/01\/1-tunel-wystawa-exponaty-wojenne-manekiny-fiat126p-turysci-768x512.jpg 768w, https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2023\/01\/1-tunel-wystawa-exponaty-wojenne-manekiny-fiat126p-turysci-300x200.jpg 300w, https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2023\/01\/1-tunel-wystawa-exponaty-wojenne-manekiny-fiat126p-turysci-1024x683.jpg 1024w, https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2023\/01\/1-tunel-wystawa-exponaty-wojenne-manekiny-fiat126p-turysci-1536x1024.jpg 1536w, https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2023\/01\/1-tunel-wystawa-exponaty-wojenne-manekiny-fiat126p-turysci-2048x1365.jpg 2048w, https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2023\/01\/elementor\/thumbs\/1-tunel-wystawa-exponaty-wojenne-manekiny-fiat126p-turysci-scaled-e1677086007468-q2jmw48rvs2niebs3aihmjeg5oawgqjdennpguyzds.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c346f6a elementor-widget elementor-widget-text-editor\" data-id=\"1c346f6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"color: #ffd200;\">\u00dcber 60 Ausstellungen<\/p>\n<p style=\"color: #ffffff;\"> das Erlebnis beginnt bereits im ehemaligen Personentunnel<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-20b5d362 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"20b5d362\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58807943 elementor-widget elementor-widget-image\" data-id=\"58807943\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/elementor\/thumbs\/2-zabytek-fiat-126p-tunel-zwiedzanie-rodzina-dla-dzieci_edited-scaled-q1f99zpkwq2ox50qu76whnin90zk0fd8r8eangpv0c.jpg\" title=\"2-zabytek-fiat-126p-tunel-zwiedzanie-rodzina-dla-dzieci_edited\" alt=\"Podziemne Trasy Szczecina\" class=\"elementor-animation-grow\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-697c4f06 elementor-widget elementor-widget-text-editor\" data-id=\"697c4f06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"color: #ffd200;\">Nimm die Familie mit<\/p><p style=\"color: #ffffff;\">auf einer Zeitreise<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3fe74907 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"3fe74907\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f256942 elementor-widget elementor-widget-image\" data-id=\"7f256942\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/elementor\/thumbs\/3-fiat126p-wnetrze-wyposazenie-rodzina-matka-corka-expozycja-czasy-prl_edited-scaled-e1677084778892-q2jm0114ke552bgxlpfiapqy0cryfjr0t4se978tzs.jpg\" title=\"3-fiat126p-wnetrze-wyposazenie-rodzina-matka-corka-expozycja-czasy-prl_edited\" alt=\"Podziemne Trasy Szczecina\" class=\"elementor-animation-grow\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26290614 elementor-widget elementor-widget-text-editor\" data-id=\"26290614\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"color: #ffd200;\">Fiat 126p<\/p>\n<p style=\"color: #ffffff;\">und Realismus der Zeit der Volksrepublik Polen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7511516 e-con-full e-flex e-con e-child\" data-id=\"7511516\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3fe88cb9 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"3fe88cb9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6564d0b7 elementor-widget elementor-widget-image\" data-id=\"6564d0b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/elementor\/thumbs\/dunel-dolny-Podziemne-trasy-atrakcja-szczecin-turystyczna-dla-dzieci-doroslych-zachodniopomorskie-scaled-q7tgi3rtub7n42yv0tl6byl8b55f7lpr1tu9l8qeo0.jpg\" title=\"dunel-dolny-Podziemne-trasy-atrakcja-szczecin-turystyczna-dla-dzieci-doros\u0142ych-zachodniopomorskie\" alt=\"Der untere Tunnel auf der Route der Besichtigung der unterirdischen Wege von Stettin, wo Touristen sich vor Schaufensterpuppen fotografieren lassen, die Menschen darstellen, die w\u00e4hrend des Zweiten Weltkriegs im Bunker sitzen\" class=\"elementor-animation-grow\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-418dde1e elementor-widget elementor-widget-text-editor\" data-id=\"418dde1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"color: #ffd200;\">Der untere Tunnel auf der Route der Besichtigung der unterirdischen Wege von Stettin<\/p><p style=\"color: #ffffff;\">\u00a0wo Touristen sich vor Schaufensterpuppen fotografieren lassen, die Menschen darstellen, die w\u00e4hrend des Zweiten Weltkriegs im Bunker sitzen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-10eed9f4 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"10eed9f4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b9302d elementor-widget elementor-widget-image\" data-id=\"8b9302d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/elementor\/thumbs\/6-trasa-II-wojna-swiatowa-wystawy-tsesler-scaled-q1f9x2mwq9okc1ms3fftosx4nc4ywzdsewy0b52bjs.jpg\" title=\"6-trasa-II-wojna-swiatowa-wystawy-tsesler\" alt=\"Podziemne Trasy Szczecina\" class=\"elementor-animation-grow\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42a5053a elementor-widget elementor-widget-text-editor\" data-id=\"42a5053a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"color: #ffd200;\">Auf zweiten Weltkriegroute<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d647542 elementor-widget elementor-widget-text-editor\" data-id=\"4d647542\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Grafiken und Collagen, die von dem Ort inspiriert sind<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ff14520 e-con-full e-flex e-con e-child\" data-id=\"ff14520\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1230dc21 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"1230dc21\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32e752f3 elementor-widget elementor-widget-image\" data-id=\"32e752f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/elementor\/thumbs\/7-zimna-wojna-trasa-zwiedzanie-schron-scaled-e1677084680982-q2jlxgwxymnlx4j0voaj1gts6fu6r3kidycn91kdz4.jpg\" title=\"7-zimna-wojna-trasa-zwiedzanie-schron\" alt=\"Podziemne Trasy Szczecina\" class=\"elementor-animation-grow\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-448b43bf elementor-widget elementor-widget-text-editor\" data-id=\"448b43bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"color: #ffd200;\">Auf der Route des Kalten Krieges<\/p>\n<p style=\"color: #ffffff;\">taktischer Raum &#8211; Propagandasendungen des Radiosenders und ein Film<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-305caaa8 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"305caaa8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-127730d3 elementor-widget elementor-widget-image\" data-id=\"127730d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/elementor\/thumbs\/8-obrona-cywilna-sekretarka-trasa-zimna-wojna-scaled-e1677084698191-q2jlxxu1dnapog40p9qkfmz2tzodh28k6xjloq7syk.jpg\" title=\"8-obrona-cywilna-sekretarka-trasa-zimna-wojna\" alt=\"Podziemne Trasy Szczecina\" class=\"elementor-animation-grow\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-124e8bb3 elementor-widget elementor-widget-text-editor\" data-id=\"124e8bb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"color: #ffd200;\">Sekretariat Zivilschutz<\/p>\n<p style=\"color: #ffffff;\">immer wachsam und bereit <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e10902b e-con-full e-flex e-con e-child\" data-id=\"7e10902b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5c6145f9 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"5c6145f9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-73f61b8f elementor-widget elementor-widget-image\" data-id=\"73f61b8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/elementor\/thumbs\/10-trasa-selfie-z-prl-plaza-e1675095814510-q1fjg3ujhknkw115miogl0k7dyekkrmgakv37drndg.jpg\" title=\"10-trasa-selfie-z-prl-pla\u017ca\" alt=\"Podziemne Trasy Szczecina\" class=\"elementor-animation-grow\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42b194aa elementor-widget elementor-widget-text-editor\" data-id=\"42b194aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"color: #ffd200;\">Selfie-Tour mit PRL<\/p>\n<p style=\"color: #ffffff;\">Es ist Zeit, sich zu entspannen und mit Gadgets aus der kommunistischen Zeit zu spielen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7db6d95b e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"7db6d95b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29c3fbfb elementor-widget elementor-widget-image\" data-id=\"29c3fbfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/elementor\/thumbs\/trasa-selfie-z-prl-rekonstrukcja-mieszkania-stoczniowca-Podziemne-trasy-szczecina-atrakcja-szczecin-turystyczna-zachodniopomorskie-1-scaled-q7ti9ta122etncjzji0wi75xg8dnwd1v2d8qy11tpc.jpg\" title=\"trasa-selfie-z-prl-rekonstrukcja-mieszkania-stoczniowca-Podziemne-trasy-szczecina-atrakcja-szczecin-turystyczna-zachodniopomorskie\" alt=\"Die Rekonstruktion der Wohnung eines Werftarbeiters aus der kommunistischen \u00c4ra der 70er Jahre entlang der Besichtigungsroute &quot;Selfie mit der Volksrepublik Polen&quot; in der Galerie f\u00fcr thematische Ausstellungen des Untergrundweges von Stettin.\" class=\"elementor-animation-grow\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32bf5bd7 elementor-widget elementor-widget-text-editor\" data-id=\"32bf5bd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"color: #ffd200;\">Aussehen der Wohnung<\/p><p style=\"color: #ffffff;\">Werftarbeiter Rysiek Koniecpolski, der \u00fcber die Vorteile des Lebens in der Volksrepublik Polen sprechen wird<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-716b0f1b e-con-full e-flex e-con e-child\" data-id=\"716b0f1b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7687d7dd e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"7687d7dd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46960821 elementor-widget elementor-widget-image\" data-id=\"46960821\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/elementor\/thumbs\/Podziemne-trasy-szczecina-wejscie-peron-1-jak-trafic-szklana-wiata-schodami-w-dol-atrakcja-szczecin-turystyczna-zachodniopomorskie-scaled-q7thcpeh10gm9x2uq8e5ptpcojfvqu66q4yvpgye4g.jpg\" title=\"Podziemne-trasy-szczecina-wej\u015bcie-peron-1-jak-trafi\u0107-szklana-wiata-schodami-w-d\u00f3\u0142&#8211;atrakcja-szczecin-turystyczna-zachodniopomorskie\" alt=\"Bahnsteig 1, Bahnhof Szczecin, Eingang in die verglaste \u00dcberdachung, Treppe hinunter zur Besichtigung der unterirdischen Wege von Stettin\" class=\"elementor-animation-grow\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5083b37c elementor-widget elementor-widget-text-editor\" data-id=\"5083b37c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"color: #ffd200;\">Von der Hauptbahnhofshalle aus gehe auf den ersten Bahnsteig<\/p>\n<p style=\"\"><font color=\"#ffffff\">Du wirst einen Glasunterstand mit alten Fotos von Stettin sehen. Gehe die Treppe hinunter<\/font><br><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6096e63e e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"6096e63e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6308402c elementor-widget elementor-widget-image\" data-id=\"6308402c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/elementor\/thumbs\/atrakcja-turystyczna-podziemne-trasy-szczecin-dworzec-pkp-scaled-r8xzgwkn1qmrkj8se2rxe0lwxjyaj5b0830mom2gay.jpg\" title=\"atrakcja-turystyczna-podziemne-trasy-szczecin-dworzec-pkp\" alt=\"foto-tunel-trasa-II Wojna \u015awiatowa-podziemne trasy szczecina turystka robi zdj\u0119cie w tunelu podczas zwiedzania\" class=\"elementor-animation-grow\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c8b63c elementor-widget elementor-widget-text-editor\" data-id=\"9c8b63c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"color: #ffd200;\">Fangen Sie die Atmosph\u00e4re des Ortes ein<\/p><p style=\"color: #ffffff;\">in einem der gr\u00f6\u00dften zivilen Schutzr\u00e4ume in Polen und Europa<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c78fe23 e-flex e-con-boxed e-con e-parent\" data-id=\"1c78fe23\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-534ae727 e-con-full e-flex e-con e-child\" data-id=\"534ae727\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bfeb3b2 e-transform elementor-invisible elementor-widget elementor-widget-image\" data-id=\"bfeb3b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-2,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;rotateInUpLeft&quot;,&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"675\" height=\"960\" src=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2023\/08\/The-Great-Escape-to-the-North-under-ground-routes-szczecin.jpg\" class=\"elementor-animation-grow attachment-medium_large size-medium_large wp-image-5478\" alt=\"The movie poster for &quot;The Great Escape North&quot; depicts two RAF pilots, Per Bergsland and Jens M\u00fcller, who in March 1944 escape from a camp in \u017baga\u0144 to Szczecin. They search for Swedish sailors and experience two intense days in the city.\" srcset=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2023\/08\/The-Great-Escape-to-the-North-under-ground-routes-szczecin.jpg 675w, https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2023\/08\/The-Great-Escape-to-the-North-under-ground-routes-szczecin-211x300.jpg 211w\" sizes=\"(max-width: 675px) 100vw, 675px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-565d0645 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"565d0645\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/youtu.be\/mdbAZ86Dy18\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Sehen Sie sich zuerst den Trailer an <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-27bd8230 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"27bd8230\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55c7ce81 e-transform elementor-widget elementor-widget-image\" data-id=\"55c7ce81\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"511\" src=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2023\/01\/UCIECZKA-11_edited-768x511.jpg\" class=\"elementor-animation-grow attachment-medium_large size-medium_large wp-image-1412\" alt=\"Podziemne Trasy Szczecina\" srcset=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2023\/01\/UCIECZKA-11_edited-768x511.jpg 768w, https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2023\/01\/UCIECZKA-11_edited-300x200.jpg 300w, https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2023\/01\/UCIECZKA-11_edited-1024x681.jpg 1024w, https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2023\/01\/UCIECZKA-11_edited-1536x1022.jpg 1536w, https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2023\/01\/UCIECZKA-11_edited-2048x1363.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">A scene from the movie The Great Escape to the North, a place on the sightseeing route<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54102f5 elementor-widget elementor-widget-heading\" data-id=\"54102f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Film<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78a1c87 elementor-widget elementor-widget-text-editor\" data-id=\"78a1c87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201eDie gro\u00dfe Flucht in den Norden\u201c <\/p>\n<p><span class=\"wysiwyg-font-size-16\">Sehen Sie sich den Film kostenlos an. Besuchen Sie den Ort, an dem es gedreht wurde. <\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c74acf1 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7c74acf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/youtu.be\/C0tEbO-URY4\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ich schaue<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Unterirdische Besichtigungsrouten in Stettin Thematische Ausstellungsgalerie Beschreibend auf Deutsch mehr als 60 Ausstellungen f\u00fcr Erwachsene und Kinder. Eine Eintrittskarte erm\u00f6glicht die individuelle Besichtigung von drei verschiedenen Routen, mit Licht, Ton, Filmen und einzigartigen Exponaten. Eingang am Bahnsteig 1. Aktuelle \u00d6ffnungszeiten Einzelbesucher Besichtigung ohne F\u00fchrer und Reservierung Do-Mo 12:00-16:00 Letzte EIntritt 15:00 Laenger im Sommer. Gruppen [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-9747","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Super Atrakcja Zwiedzanie - Der Unterirdischen Besichtigungsrouten in Stettin - Thematische Ausstellungsgalerie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schron.szczecin.pl\/de\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Super Atrakcja Zwiedzanie - Der Unterirdischen Besichtigungsrouten in Stettin - Thematische Ausstellungsgalerie\" \/>\n<meta property=\"og:description\" content=\"Unterirdische Besichtigungsrouten in Stettin Thematische Ausstellungsgalerie Beschreibend auf Deutsch mehr als 60 Ausstellungen f\u00fcr Erwachsene und Kinder. Eine Eintrittskarte erm\u00f6glicht die individuelle Besichtigung von drei verschiedenen Routen, mit Licht, Ton, Filmen und einzigartigen Exponaten. Eingang am Bahnsteig 1. Aktuelle \u00d6ffnungszeiten Einzelbesucher Besichtigung ohne F\u00fchrer und Reservierung Do-Mo 12:00-16:00 Letzte EIntritt 15:00 Laenger im Sommer. Gruppen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schron.szczecin.pl\/de\/\" \/>\n<meta property=\"og:site_name\" content=\"Der Unterirdischen Besichtigungsrouten in Stettin - Thematische Ausstellungsgalerie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T13:54:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2025\/02\/trasy-piktogram-ludziki.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schron.szczecin.pl\\\/de\\\/\",\"url\":\"https:\\\/\\\/schron.szczecin.pl\\\/de\\\/\",\"name\":\"Super Atrakcja Zwiedzanie - Der Unterirdischen Besichtigungsrouten in Stettin - Thematische Ausstellungsgalerie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schron.szczecin.pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schron.szczecin.pl\\\/de\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schron.szczecin.pl\\\/de\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schron.szczecin.pl\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/trasy-piktogram-ludziki.png\",\"datePublished\":\"2026-01-28T11:24:17+00:00\",\"dateModified\":\"2026-05-06T13:54:42+00:00\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schron.szczecin.pl\\\/de\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/schron.szczecin.pl\\\/de\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schron.szczecin.pl\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/trasy-piktogram-ludziki.png\",\"contentUrl\":\"https:\\\/\\\/schron.szczecin.pl\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/trasy-piktogram-ludziki.png\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schron.szczecin.pl\\\/#website\",\"url\":\"https:\\\/\\\/schron.szczecin.pl\\\/\",\"name\":\"Der Unterirdischen Besichtigungsrouten in Stettin - Thematische Ausstellungsgalerie\",\"description\":\"Beschreibend auf Deutsch mehr als 60 Ausstellungen f\u00fcr Erwachsene und Kinder. Eine Eintrittskarte erm\u00f6glicht die individuelle Besichtigung von drei verschiedenen Routen, mit Licht, Ton, Filmen und einzigartigen Exponaten. Eingang am Bahnsteig 1.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schron.szczecin.pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Super Atrakcja Zwiedzanie - Der Unterirdischen Besichtigungsrouten in Stettin - Thematische Ausstellungsgalerie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schron.szczecin.pl\/de\/","og_locale":"de_DE","og_type":"article","og_title":"Super Atrakcja Zwiedzanie - Der Unterirdischen Besichtigungsrouten in Stettin - Thematische Ausstellungsgalerie","og_description":"Unterirdische Besichtigungsrouten in Stettin Thematische Ausstellungsgalerie Beschreibend auf Deutsch mehr als 60 Ausstellungen f\u00fcr Erwachsene und Kinder. Eine Eintrittskarte erm\u00f6glicht die individuelle Besichtigung von drei verschiedenen Routen, mit Licht, Ton, Filmen und einzigartigen Exponaten. Eingang am Bahnsteig 1. Aktuelle \u00d6ffnungszeiten Einzelbesucher Besichtigung ohne F\u00fchrer und Reservierung Do-Mo 12:00-16:00 Letzte EIntritt 15:00 Laenger im Sommer. Gruppen [&hellip;]","og_url":"https:\/\/schron.szczecin.pl\/de\/","og_site_name":"Der Unterirdischen Besichtigungsrouten in Stettin - Thematische Ausstellungsgalerie","article_modified_time":"2026-05-06T13:54:42+00:00","og_image":[{"url":"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2025\/02\/trasy-piktogram-ludziki.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schron.szczecin.pl\/de\/","url":"https:\/\/schron.szczecin.pl\/de\/","name":"Super Atrakcja Zwiedzanie - Der Unterirdischen Besichtigungsrouten in Stettin - Thematische Ausstellungsgalerie","isPartOf":{"@id":"https:\/\/schron.szczecin.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schron.szczecin.pl\/de\/#primaryimage"},"image":{"@id":"https:\/\/schron.szczecin.pl\/de\/#primaryimage"},"thumbnailUrl":"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2025\/02\/trasy-piktogram-ludziki.png","datePublished":"2026-01-28T11:24:17+00:00","dateModified":"2026-05-06T13:54:42+00:00","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schron.szczecin.pl\/de\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/schron.szczecin.pl\/de\/#primaryimage","url":"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2025\/02\/trasy-piktogram-ludziki.png","contentUrl":"https:\/\/schron.szczecin.pl\/wp-content\/uploads\/2025\/02\/trasy-piktogram-ludziki.png"},{"@type":"WebSite","@id":"https:\/\/schron.szczecin.pl\/#website","url":"https:\/\/schron.szczecin.pl\/","name":"Der Unterirdischen Besichtigungsrouten in Stettin - Thematische Ausstellungsgalerie","description":"Beschreibend auf Deutsch mehr als 60 Ausstellungen f\u00fcr Erwachsene und Kinder. Eine Eintrittskarte erm\u00f6glicht die individuelle Besichtigung von drei verschiedenen Routen, mit Licht, Ton, Filmen und einzigartigen Exponaten. Eingang am Bahnsteig 1.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schron.szczecin.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/schron.szczecin.pl\/de\/wp-json\/wp\/v2\/pages\/9747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schron.szczecin.pl\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/schron.szczecin.pl\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/schron.szczecin.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/schron.szczecin.pl\/de\/wp-json\/wp\/v2\/comments?post=9747"}],"version-history":[{"count":101,"href":"https:\/\/schron.szczecin.pl\/de\/wp-json\/wp\/v2\/pages\/9747\/revisions"}],"predecessor-version":[{"id":10501,"href":"https:\/\/schron.szczecin.pl\/de\/wp-json\/wp\/v2\/pages\/9747\/revisions\/10501"}],"wp:attachment":[{"href":"https:\/\/schron.szczecin.pl\/de\/wp-json\/wp\/v2\/media?parent=9747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}